{"id":4522,"date":"2022-12-12T13:15:49","date_gmt":"2022-12-12T11:15:49","guid":{"rendered":"https:\/\/cbrpalestine.org\/Site\/feedback\/"},"modified":"2024-02-03T18:40:59","modified_gmt":"2024-02-03T16:40:59","slug":"feedback","status":"publish","type":"page","link":"https:\/\/cbrpalestine.org\/ar\/feedback\/","title":{"rendered":"\u0627\u0644\u062a\u063a\u0630\u064a\u0629 \u0627\u0644\u0627\u0633\u062a\u0631\u062c\u0627\u0639\u064a\u0629 \u0648\u0627\u0644\u0634\u0643\u0627\u0648\u0649"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4522\" class=\"elementor elementor-4522 elementor-3318\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0857de9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0857de9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c078a04\" data-id=\"c078a04\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab6be4c elementor-widget elementor-widget-cf7 bdevs-el cf7\" data-id=\"ab6be4c\" data-element_type=\"widget\" data-settings=\"{&quot;design_style&quot;:&quot;style_2&quot;}\" data-widget_type=\"cf7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t                    <div class=\"get_intouch_area\">\n                <div class=\"container\">\n                    <div class=\"row\">\n                        <div class=\"col-xxl-6 col-xl-6 col-lg-7 order-1 order-lg-0\">\n                            <div class=\"contact_section contact_contact bottom_radius0\">\n                                \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f4654-o1\" lang=\"ar\" dir=\"rtl\" data-wpcf7-id=\"4654\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/ar\/wp-json\/wp\/v2\/pages\/4522#wpcf7-f4654-o1\" method=\"post\" class=\"wpcf7-form init bdevs-cf7-form\" aria-label=\"\u0646\u0645\u0648\u0630\u062c \u0627\u0644\u0627\u062a\u0635\u0627\u0644\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"4654\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.2\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"ar\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f4654-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><label> \u0627\u0633\u0645\u0643<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> \u0628\u0631\u064a\u062f\u0643 \u0627\u0644\u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> \u0645\u0648\u0636\u0648\u0639\u0627\u062a<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span> <\/label>\n<\/p>\n<p><label> \u0631\u0633\u0627\u0644\u062a\u0643<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Submit\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"80\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n                            <\/div>\n                        <\/div>\n                        <div class=\"col-xxl-6 col-xl-6 col-lg-5 order-0 order-lg-1\">\n                            <div class=\"contact_location_section pl-50 mb-50\">\n                                <div class=\"section_title mb-40\">\n                                                                            <span class=\"sub_title sub_title_2\">If you have a general feedback, please fill in the form: <\/span>\n                                    \n                                                                            <h3 class=\"title\">General Feedback<\/h3>\n                                                                    <\/div>\n\n                                <div class=\"contact_location_wrapper\">\n                                                                            <div class=\"single_contact_location theme-1\">\n                                            <div class=\"icon\">\n                                                                                                    <figure>\n                                                        <i aria-hidden=\"true\" class=\"fas fa-phone\"><\/i>                                                    <\/figure>\n                                                                                            <\/div>\n\n                                            <div class=\"contact_location_text\">\n                                                                                                    <span>Telephone support<\/span>\n                                                \n                                                                                                    <a href=\"tel:+97022749793\" class=\"contact_address_title\">+970 (2) 274 9793<\/a>\n                                                                                            <\/div>\n                                        <\/div>\n                                                                            <div class=\"single_contact_location theme-1\">\n                                            <div class=\"icon\">\n                                                                                                    <figure>\n                                                        <i aria-hidden=\"true\" class=\"fas fa-fax\"><\/i>                                                    <\/figure>\n                                                                                            <\/div>\n\n                                            <div class=\"contact_location_text\">\n                                                                                                    <span>Fax<\/span>\n                                                \n                                                                                                    <a href=\"tel:97022749001\" class=\"contact_address_title\">+970 (2) 274 9001<\/a>\n                                                                                            <\/div>\n                                        <\/div>\n                                                                            <div class=\"single_contact_location theme-1\">\n                                            <div class=\"icon\">\n                                                                                                    <figure>\n                                                        <i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>                                                    <\/figure>\n                                                                                            <\/div>\n\n                                            <div class=\"contact_location_text\">\n                                                                                                    <span>Email Support<\/span>\n                                                \n                                                                                                    <a href=\"mailto:cbrsouth@cbrsouth.org\" class=\"contact_address_title\">cbrsouth@cbrsouth.org<\/a>\n                                                                                            <\/div>\n                                        <\/div>\n                                                                            <div class=\"single_contact_location theme-1\">\n                                            <div class=\"icon\">\n                                                                                                    <figure>\n                                                        <i aria-hidden=\"true\" class=\"fas fa-map-marked\"><\/i>                                                    <\/figure>\n                                                                                            <\/div>\n\n                                            <div class=\"contact_location_text\">\n                                                                                                    <span>CBR Office Address<\/span>\n                                                \n                                                                                                    <a href=\"https:\/\/goo.gl\/maps\/vLUjhbXFwPHTitcZA\" class=\"contact_address_title\">Al-Nozha Street,  Beit Jala - Palestine.<\/a>\n                                                                                            <\/div>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        \n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e90f044 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e90f044\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e94887\" data-id=\"1e94887\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6219e5a elementor-widget elementor-widget-spacer\" data-id=\"6219e5a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a897ebf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a897ebf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f681046\" data-id=\"f681046\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af05e1a elementor-widget elementor-widget-infobox bdevs-el infobox\" data-id=\"af05e1a\" data-element_type=\"widget\" data-settings=\"{&quot;design_style&quot;:&quot;style_1&quot;}\" data-widget_type=\"infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t                    <div class=\"services_single mb-30 bdevs-infobox-body\">\n                                <div class=\"services_text\">\n                                        <h5 class=\"services_title bdevs-infobox-title\"><a href=\"\">SEA Complaints <\/a><\/h5>\n                                            <p class=\"bdevs-infobox-text \" >If you have a complaint regarding sexual harassment and assault, please click the button below and send it to <a class=\"theme-2\" href=\"mailto:cbrsouth@cbrsouth.org\">cbrsouth@cbrsouth.org<\/a>.<\/p>\n                    \n\n                    <div class=\"sv-btn\">\n                        <a class=\"service_btn btn\" href=\"https:\/\/cbrpalestine.org\/Site\/wp-content\/uploads\/2022\/12\/\u0646\u0645\u0648\u0630\u062c-\u0634\u0643\u0648\u0649.pdf\" target=\"_blank\">SEA Form<\/a>                    <\/div>\n                <\/div>\n            <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Your name Your email Subject Your message &#916; If you have a general feedback, please fill in the form: General Feedback Telephone support +970 (2) 274 9793 Fax +970 (2) [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4522","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/cbrpalestine.org\/ar\/wp-json\/wp\/v2\/pages\/4522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbrpalestine.org\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cbrpalestine.org\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cbrpalestine.org\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cbrpalestine.org\/ar\/wp-json\/wp\/v2\/comments?post=4522"}],"version-history":[{"count":2,"href":"https:\/\/cbrpalestine.org\/ar\/wp-json\/wp\/v2\/pages\/4522\/revisions"}],"predecessor-version":[{"id":5644,"href":"https:\/\/cbrpalestine.org\/ar\/wp-json\/wp\/v2\/pages\/4522\/revisions\/5644"}],"wp:attachment":[{"href":"https:\/\/cbrpalestine.org\/ar\/wp-json\/wp\/v2\/media?parent=4522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}